{"id":8736,"count":2,"description":"","link":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/","name":"Cestas de mercado na zona norte","slug":"cestas-de-mercado-na-zona-norte","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arquivos Cestas de mercado na zona norte - CRR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Cestas de mercado na zona norte - CRR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"CRR\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/\",\"url\":\"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/\",\"name\":\"Arquivos Cestas de mercado na zona norte - CRR\",\"isPartOf\":{\"@id\":\"https:\/\/www.crr.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.crr.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cestas de mercado na zona norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.crr.com.br\/blog\/#website\",\"url\":\"https:\/\/www.crr.com.br\/blog\/\",\"name\":\"CRR\",\"description\":\"Blog - CRR\",\"publisher\":{\"@id\":\"https:\/\/www.crr.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.crr.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.crr.com.br\/blog\/#organization\",\"name\":\"CRR Com\u00e9rcio de Rolamentos\",\"url\":\"https:\/\/www.crr.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.crr.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/crr.com.br\/wp-content\/uploads\/2019\/08\/logo.png\",\"contentUrl\":\"https:\/\/crr.com.br\/wp-content\/uploads\/2019\/08\/logo.png\",\"width\":140,\"height\":103,\"caption\":\"CRR Com\u00e9rcio de Rolamentos\"},\"image\":{\"@id\":\"https:\/\/www.crr.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Cestas de mercado na zona norte - CRR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Cestas de mercado na zona norte - CRR","og_url":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/","og_site_name":"CRR","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/","url":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/","name":"Arquivos Cestas de mercado na zona norte - CRR","isPartOf":{"@id":"https:\/\/www.crr.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.crr.com.br\/blog\/tag\/cestas-de-mercado-na-zona-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.crr.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Cestas de mercado na zona norte"}]},{"@type":"WebSite","@id":"https:\/\/www.crr.com.br\/blog\/#website","url":"https:\/\/www.crr.com.br\/blog\/","name":"CRR","description":"Blog - CRR","publisher":{"@id":"https:\/\/www.crr.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.crr.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.crr.com.br\/blog\/#organization","name":"CRR Com\u00e9rcio de Rolamentos","url":"https:\/\/www.crr.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.crr.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/crr.com.br\/wp-content\/uploads\/2019\/08\/logo.png","contentUrl":"https:\/\/crr.com.br\/wp-content\/uploads\/2019\/08\/logo.png","width":140,"height":103,"caption":"CRR Com\u00e9rcio de Rolamentos"},"image":{"@id":"https:\/\/www.crr.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.crr.com.br\/blog\/wp-json\/wp\/v2\/tags\/8736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.crr.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.crr.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.crr.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=8736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}